{"id":179,"count":21,"description":"","link":"https:\/\/domuslux.gr\/el\/features\/buildable\/","name":"\u039f\u03b9\u03ba\u03bf\u03b4\u03bf\u03bc\u03ae\u03c3\u03b9\u03bc\u03bf","slug":"buildable","taxonomy":"features","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buildable Archives - Domus Lux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/domuslux.gr\/el\/features\/buildable\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buildable Archives - Domus Lux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/domuslux.gr\/el\/features\/buildable\/\" \/>\n<meta property=\"og:site_name\" content=\"Domus Lux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/domuslux.gr\\\/features\\\/buildable\\\/\",\"url\":\"https:\\\/\\\/domuslux.gr\\\/features\\\/buildable\\\/\",\"name\":\"Buildable Archives - Domus Lux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/domuslux.gr\\\/features\\\/buildable\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/domuslux.gr\\\/features\\\/buildable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/domuslux.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buildable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#website\",\"url\":\"https:\\\/\\\/domuslux.gr\\\/\",\"name\":\"Domus Lux\",\"description\":\"real estate\",\"publisher\":{\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/domuslux.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#organization\",\"name\":\"Domus Lux\",\"url\":\"https:\\\/\\\/domuslux.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/domuslux.gr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/370590534_147563128348990_6600070575522100710_n.jpg\",\"contentUrl\":\"https:\\\/\\\/domuslux.gr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/370590534_147563128348990_6600070575522100710_n.jpg\",\"width\":2048,\"height\":1205,\"caption\":\"Domus Lux\"},\"image\":{\"@id\":\"https:\\\/\\\/domuslux.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61551994081584&locale=el_GR\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buildable Archives - Domus Lux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/domuslux.gr\/el\/features\/buildable\/","og_locale":"el_GR","og_type":"article","og_title":"Buildable Archives - Domus Lux","og_url":"https:\/\/domuslux.gr\/el\/features\/buildable\/","og_site_name":"Domus Lux","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/domuslux.gr\/features\/buildable\/","url":"https:\/\/domuslux.gr\/features\/buildable\/","name":"Buildable Archives - Domus Lux","isPartOf":{"@id":"https:\/\/domuslux.gr\/#website"},"breadcrumb":{"@id":"https:\/\/domuslux.gr\/features\/buildable\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/domuslux.gr\/features\/buildable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/domuslux.gr\/"},{"@type":"ListItem","position":2,"name":"Buildable"}]},{"@type":"WebSite","@id":"https:\/\/domuslux.gr\/#website","url":"https:\/\/domuslux.gr\/","name":"Domus Lux","description":"real estate","publisher":{"@id":"https:\/\/domuslux.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/domuslux.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/domuslux.gr\/#organization","name":"Domus Lux","url":"https:\/\/domuslux.gr\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/domuslux.gr\/#\/schema\/logo\/image\/","url":"https:\/\/domuslux.gr\/wp-content\/uploads\/2023\/11\/370590534_147563128348990_6600070575522100710_n.jpg","contentUrl":"https:\/\/domuslux.gr\/wp-content\/uploads\/2023\/11\/370590534_147563128348990_6600070575522100710_n.jpg","width":2048,"height":1205,"caption":"Domus Lux"},"image":{"@id":"https:\/\/domuslux.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61551994081584&locale=el_GR"]}]}},"_links":{"self":[{"href":"https:\/\/domuslux.gr\/el\/wp-json\/wp\/v2\/features\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/domuslux.gr\/el\/wp-json\/wp\/v2\/features"}],"about":[{"href":"https:\/\/domuslux.gr\/el\/wp-json\/wp\/v2\/taxonomies\/features"}],"wp:post_type":[{"href":"https:\/\/domuslux.gr\/el\/wp-json\/wp\/v2\/estate?features=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}